{"id":1946,"date":"2025-02-06T15:39:05","date_gmt":"2025-02-06T14:39:05","guid":{"rendered":"http:\/\/www.ceramicaflaminia.com\/?page_id=1946"},"modified":"2025-02-06T15:39:05","modified_gmt":"2025-02-06T14:39:05","slug":"cookies-policy","status":"publish","type":"page","link":"https:\/\/www.ceramicaflaminia.com\/it_it\/cookies-policy\/","title":{"rendered":"Cookies Policy"},"content":{"rendered":"\n<p>Il sito web www.ceramicaflaminia.com (in seguito, \u201cSito\u201d) fa uso di cookie. Di seguito \u00e8 possibile trovare maggiori informazioni in merito ai cookie, come vengono utilizzati nel Sito e quali procedure di controllo adottiamo rispetto ai cookie stessi. Accettando il nostro banner, acconsente all\u2019utilizzo dei cookie, in conformit\u00e0 con la presente Cookie Policy.<\/p>\n\n\n\n<p><strong>C<\/strong><strong>HE COSA SONO I COOKIE?<\/strong><\/p>\n\n\n\n<p>I cookie sono piccoli file di testo che vengono salvati sul dispositivo elettronico (PC, tablet, etc.) durante la navigazione in un sito web e che forniscono determinate informazioni (\u201cCookies\u201d). I Cookies vengono poi rinviati al sito web di origine nel corso di ogni successiva navigazione, oppure vengono inviati ad un diverso sito web in grado di riconoscere quello specifico Cookie. I Cookies agiscono come una memoria per un sito web, consentendo al sito web di riconoscere i device ad ogni sua successiva visita. I Cookies consentono inoltre di memorizzare le preferenze di navigazione offrendo un\u2019esperienza pi\u00f9 funzionale del Sito,&nbsp; rendendo il contenuto del sito il pi\u00f9 personalizzato possibile.<\/p>\n\n\n\n<p>I browser web consentono di esercitare un certo controllo sui Cookies attraverso le impostazioni del browser. La maggior parte dei browser consente di bloccare i Cookies o bloccare i Cookies di determinati siti. I browser possono anche aiutare ad eliminare i Cookies quando il browser viene chiuso. Tuttavia, \u00e8 importante tenere a mente che eventuali opt-out o preferenze impostate sul sito andranno persi. Invitiamo a consultare le informazioni tecniche relative al suo browser per le istruzioni. Se si sceglie di disabilitare l\u2019impostazione dei Cookies o se si rifiuta di accettare un Cookie, alcune parti del servizio potrebbero non funzionare correttamente o potrebbero risultare notevolmente pi\u00f9 lente.<\/p>\n\n\n\n<p><strong>T<\/strong><strong>IPOLOGIE DI COOKIE<\/strong><\/p>\n\n\n\n<p>I Cookies possono essere tecnici, analitici e di profilazione.<\/p>\n\n\n\n<p><strong>Cookies Tecnici<\/strong><\/p>\n\n\n\n<p>I Cookies tecnici consentono di migliorare la navigazione e di fornire tutti i servizi offerti dal Sito. In particolare, il Sito utilizza i seguenti Cookies tecnici \u201cdi sessione\u201d e persistenti proprietari:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Cookie<\/td><td>scadenza<\/td><\/tr><tr><td>cookieconsent_status<\/td><td>7 giorni<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Cookies Analitici<\/strong><\/p>\n\n\n\n<p>I Cookies analitici ci consentono di analizzare il modo di navigare sul Sito di un utente al fine di aiutare a migliorare l\u2019esperienza di navigazione. In particolare, il Sito fa uso dei seguenti Cookies analitici:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Cookie<\/td><td>Scadenza<\/td><td>Descrizione e forntiore<\/td><\/tr><tr><td>_ga<\/td><td>2 anni<\/td><td>Fornito da Google.com ed utilizzato per distinguere gli utenti.<\/td><\/tr><tr><td>_gid<\/td><td>24 ore<\/td><td>Fornito da Google.com ed utilizzato per distinguere gli utenti.<\/td><\/tr><tr><td>_gat<\/td><td>1 minuto<\/td><td>Fornito da Google.com ed utilizzato per limitare la frequenza delle richieste.<\/td><\/tr><tr><td>AMP_TOKEN<\/td><td>Da 30 secondi ad 1 anno<\/td><td>Fornito da Google.com ed utilizzato per recuperare un ID client dal servizio ID client AMP. Per saperne di pi\u00f9 si rimanda alla Privacy Policy del fornitore.<\/td><\/tr><tr><td>_gac_&lt;property-id&gt;<\/td><td>90 giorni<\/td><td>Fornito da Google.com ed utilizzato per raccogliere informazioni relative alla campagna per l\u2019utente. Se sono collegati gli account Google, i tag di conversione del Sito di Google Ads leggeranno questo cookie a meno che non vengano disattivi. Per saperne di pi\u00f9 si rimanda alla Privacy Policy del fornitore.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Cookies di profilazione<\/strong><\/p>\n\n\n\n<p>Il Sito non fa uso di cookies di profilazione.<\/p>\n\n\n\n<p><strong>FINALIT\u00c0<\/strong><\/p>\n\n\n\n<p>I Cookies tecnici usati dal nostro Sito servono a semplificare navigazione e utilizzo dei servizi del mentre i Cookies analitici servono ad analizzare e monitorare il modo in cui il sito viene utilizzato (ad es. numero di accessi e pagine viste), a fini statistici e per permetterci di apportare modifiche migliorative in termini di funzionamento e navigazione.<\/p>\n\n\n\n<p>Il conferimento dei dati, ad eccezione di quelli raccolti mediante i Cookies tecnici, \u00e8 facoltativo.<\/p>\n\n\n\n<p><strong>COME&nbsp;CONTROLLARE ED ELIMINARE I COOKIE<\/strong><\/p>\n\n\n\n<p>\u00c8 possibile autorizzare l\u2019utilizzo dei Cookies accettando il Banner oppure si pu\u00f2 non autorizzare l\u2019utilizzo di Cookie o disattivarli in un secondo momento, procedendo manualmente alla modifica della configurazione del browser seguendo le istruzioni contenute nelle policy dei gestori dei Cookie.<\/p>\n\n\n\n<p><strong>Come disabilitare i cookies:<\/strong><\/p>\n\n\n\n<p>avvertenza: il conferimento dei dati \u00e8 facoltativo; si fa tuttavia presente che il rifiuto\/disattivazione dei cookies potr\u00e0 impedire di utilizzare alcune funzionalit\u00e0 del Sito.<\/p>\n\n\n\n<p>Chrome | Firefox | IE | Safari<\/p>\n\n\n\n<p>Se si utilizza un browser Web non presente nell\u2019elenco riportato sopra, si prega di fare riferimento alla documentazione o alla guida online del proprio browser per ottenere ulteriori informazioni. Si avvisano gli utenti che il Titolare funge da mero intermediario tecnico per i link riportati in questo documento e non pu\u00f2 assumersi nessuna responsabilit\u00e0 in caso di eventuale modifica.<\/p>\n\n\n\n<p>Per maggiori informazioni sui Cookies, eventuali modifiche delle impostazioni del device da parte dei cookies, gestione ed eliminazione, accedere al seguente link&nbsp;<a href=\"http:\/\/www.aboutcookies.org\/\">www.aboutcookies.org<\/a>.<\/p>\n\n\n\n<p>Per informazioni su: Modalit\u00e0 del trattamento, Accesso ai dati, Comunicazione dei dati, Diritti dell\u2019interessato, Modalit\u00e0 di esercizio dei diritti, Titolare, responsabili e incaricati, vi \u00e8 la nostra Informativa sul trattamento dei dati del sito web.<\/p>\n\n\n\n<p><strong>CONTATTI<\/strong> Per qualunque informazione in merito alla presente informativa, si prega di contattare l\u2019indirizzo e-mail:\u00a0<a href=\"mailto:info@ceramicaflaminia.com\">info@ceramicaflaminia.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sito web www.ceramicaflaminia.com (in seguito, \u201cSito\u201d) fa uso di cookie. Di seguito \u00e8 possibile trovare maggiori informazioni in merito ai cookie, come vengono utilizzati nel Sito e quali procedure di controllo adottiamo rispetto ai cookie stessi. Accettando il nostro banner, acconsente all\u2019utilizzo dei cookie, in conformit\u00e0 con la presente Cookie Policy. CHE COSA SONO&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1946","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/pages\/1946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":1,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/pages\/1946\/revisions"}],"predecessor-version":[{"id":1947,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/pages\/1946\/revisions\/1947"}],"wp:attachment":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/media?parent=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}