{"id":2557,"date":"2025-07-10T13:54:50","date_gmt":"2025-07-10T11:54:50","guid":{"rendered":"https:\/\/www.ceramicaflaminia.com\/?post_type=dt_portfolio&#038;p=2557"},"modified":"2025-09-04T18:13:46","modified_gmt":"2025-09-04T16:13:46","slug":"surface2","status":"publish","type":"dt_portfolio","link":"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/surface2\/","title":{"rendered":"Surface"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_custom_1754053460019\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div {\n  width: 36px;\n  height: 36px;\n  border-radius: 500px;\n}\n.dt-arrow-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:not(:hover):before {\n  border-width: 0px;\n}\n.dt-arrow-hover-border-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:hover:after {\n  border-width: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-prev {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  left: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-next {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  right: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav i {\n  font-size: 18px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:not(:hover) i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: #ffffff;\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:hover i,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f .owl-dots {\n  top: calc(100% + 20px);\n  right: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f .owl-dot {\n  width: 5px;\n  height: 5px;\n  margin: 0 4px;\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.hide-arrows .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.reposition-arrows .owl-nav .owl-prev {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    left: 10px;\n  }\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.reposition-arrows .owl-nav .owl-next {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    right: 10px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.reposition-arrows .owl-nav .owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.reposition-arrows .owl-nav .owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f figure,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f .rollover,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f img,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f .gallery-rollover {\n  border-radius: 0px;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.enable-bg-rollover .gallery-rollover {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.enable-img-shadow .owl-stage-outer {\n  padding: 14px 0;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.enable-bg-rollover.hover-scale figure .rollover:after {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.gallery-shortcode .gallery-zoom-ico {\n  width: 44px;\n  height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  margin: -22px 0 0 -22px;\n  border-width: 0px;\n}\n.dt-icon-bg-on.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.gallery-shortcode .gallery-zoom-ico {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.gallery-shortcode .gallery-zoom-ico:before,\n.gallery-carousel-shortcode.gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f.gallery-shortcode .gallery-zoom-ico span {\n  font-size: 32px;\n  line-height: 44px;\n  color: #ffffff;\n  background: none;\n}\n<\/style><div class=\"owl-carousel gallery-carousel-shortcode gallery-shortcode  dt-gallery-container dt-owl-carousel-call gallery-carousel-shortcode-id-76160c8a5b4303d35d9253ca4c37321f enable-bg-rollover meta-info-off dt-arrow-border-on dt-arrow-hover-border-on bullets-scale-up reposition-arrows dt-icon-bg-off arrows-bg-on disable-arrows-hover-bg arrows-hover-bg-on  hover-fade \" data-scroll-mode=\"1\" data-col-num=\"1\" data-wide-col-num=\"1\" data-laptop-col=\"1\" data-h-tablet-columns-num=\"1\" data-v-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-col-gap=\"10\" data-stage-padding=\"0\" data-speed=\"400\" data-autoplay=\"true\" data-autoplay_speed=\"4000\" data-arrows=\"false\" data-bullet=\"true\" data-next-icon=\"icon-ar-017-r\" data-prev-icon=\"icon-ar-017-l\" data-img-shadow-size=\"12px\" data-img-shadow-spread=\"3px\"><div data-post-id=\"2884\" data-date=\"2025-08-01T15:14:41+02:00\" data-name=\"Surface-amb_1\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_1.jpg\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"2000\" data-large_image_height=\"815\" data-dt-img-description=\"\" title=\"Surface-amb_1\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%202000%20815&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_1.jpg\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_1.jpg 2000w\" loading=\"eager\" style=\"--ratio: 2000 \/ 815\" sizes=\"(max-width: 2000px) 100vw, 2000px\" alt=\"\" width=\"2000\" height=\"815\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div data-post-id=\"3139\" data-date=\"2025-09-04T18:13:07+02:00\" data-name=\"SURFACE SAND\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-SAND.png\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1477\" data-large_image_height=\"602\" data-dt-img-description=\"\" title=\"SURFACE SAND\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%201477%20602&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-SAND.png\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-SAND.png 1477w\" loading=\"eager\" style=\"--ratio: 1477 \/ 602\" sizes=\"(max-width: 1477px) 100vw, 1477px\" alt=\"\" width=\"1477\" height=\"602\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div data-post-id=\"2885\" data-date=\"2025-08-01T15:14:42+02:00\" data-name=\"Surface-amb_2\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_2.jpg\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"2000\" data-large_image_height=\"815\" data-dt-img-description=\"\" title=\"Surface-amb_2\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%202000%20815&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_2.jpg\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_2.jpg 2000w\" loading=\"eager\" style=\"--ratio: 2000 \/ 815\" sizes=\"(max-width: 2000px) 100vw, 2000px\" alt=\"\" width=\"2000\" height=\"815\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div data-post-id=\"3140\" data-date=\"2025-09-04T18:13:11+02:00\" data-name=\"SURFACE WHITE\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-WHITE.png\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1477\" data-large_image_height=\"602\" data-dt-img-description=\"\" title=\"SURFACE WHITE\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%201477%20602&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-WHITE.png\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-WHITE.png 1477w\" loading=\"eager\" style=\"--ratio: 1477 \/ 602\" sizes=\"(max-width: 1477px) 100vw, 1477px\" alt=\"\" width=\"1477\" height=\"602\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div data-post-id=\"2886\" data-date=\"2025-08-01T15:14:43+02:00\" data-name=\"Surface-amb_3\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_3.jpg\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"2000\" data-large_image_height=\"815\" data-dt-img-description=\"\" title=\"Surface-amb_3\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%202000%20815&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_3.jpg\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Surface-amb_3.jpg 2000w\" loading=\"eager\" style=\"--ratio: 2000 \/ 815\" sizes=\"(max-width: 2000px) 100vw, 2000px\" alt=\"\" width=\"2000\" height=\"815\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><div data-post-id=\"3138\" data-date=\"2025-09-04T18:13:04+02:00\" data-name=\"SURFACE GREIGE\"><figure class=\"post\"><a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-GREIGE.png\" class=\"rollover dt-pswp-item layzr-bg\" data-large_image_width=\"1477\" data-large_image_height=\"602\" data-dt-img-description=\"\" title=\"SURFACE GREIGE\"><img decoding=\"async\" class=\"preload-me owl-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%201477%20602&#39;%2F%3E\" data-src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-GREIGE.png\" data-srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/SURFACE-GREIGE.png 1477w\" loading=\"eager\" style=\"--ratio: 1477 \/ 602\" sizes=\"(max-width: 1477px) 100vw, 1477px\" alt=\"\" width=\"1477\" height=\"602\"  \/><span class=\"gallery-rollover\"><\/span><\/a><\/figure><\/div><\/div><div class=\"ult-spacer spacer-6a045163e7e7f\" data-id=\"6a045163e7e7f\" data-height=\"120\" data-height-mobile=\"40\" data-height-tab=\"80\" data-height-tab-portrait=\"80\" data-height-mobile-landscape=\"40\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1752148151839 new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1><span style=\"color: #636363;\">SURFACE<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_row-o-equal-height vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1752148202286\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: left;\">Surface di Ceramica Flaminia \u00e8 una collezione di piastrelle in gres porcellanato che esplora la materia con superfici minimali e sofisticate. Proposta nei colori White, Greige e Sand, e nei formati rettificati 60\u00d760, 90\u00d790 e 60\u00d7120, si distingue per la sua texture morbida e neutra, capace di valorizzare ambienti moderni con equilibrio e sobriet\u00e0. Surface \u00e8 la scelta ideale per progetti che richiedono versatilit\u00e0, eleganza e continuit\u00e0 estetica tra pavimenti e rivestimenti.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\" vc_custom_1752148212672 ubtn-ctn-right \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-right ubtn-mini \" href=\"http:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/06\/SURFACE-INDOOR.pdf\" target=\"_blank\" rel=\"noopener\" ><button type=\"button\" id=\"ubtn-7931\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-mini ubtn-no-hover-bg  ulta-grow  ubtn-sep-icon ubtn-sep-icon-at-left  ubtn-right   tooltip-6a045163e84c6\"  data-hover=\"rgba(0,0,0,0.82)\" data-border-color=\"\" data-bg=\"#e0e0e0\" data-hover-bg=\"\" data-border-hover=\"\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-7931'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;border:none;background: #e0e0e0;color: #636363;\"><span class=\"ubtn-data ubtn-icon\"><i class=\"dt-icon-the7-download\" style=\"font-size:0px;color:#c38839;\"><\/i><\/span><span class=\"ubtn-hover\" style=\"background-color:\"><\/span><span class=\"ubtn-data ubtn-text \" >SCARICA LA SCHEDA TECNICA<\/span><\/button><\/a><\/div><div class=\" vc_custom_1754576853783 ubtn-ctn-right \"><a class=\"ubtn-link ult-adjust-bottom-margin ubtn-right ubtn-mini \" href=\"http:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/08\/SURFACE_low.pdf\" target=\"_blank\" rel=\"noopener\" ><button type=\"button\" id=\"ubtn-2044\"  class=\"ubtn ult-adjust-bottom-margin ult-responsive ubtn-mini ubtn-no-hover-bg  ulta-grow  ubtn-sep-icon ubtn-sep-icon-at-left  ubtn-right   tooltip-6a045163e8504\"  data-hover=\"rgba(0,0,0,0.82)\" data-border-color=\"\" data-bg=\"#e0e0e0\" data-hover-bg=\"\" data-border-hover=\"\" data-shadow-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" data-shd-shadow=\"\"  data-ultimate-target='#ubtn-2044'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;border:none;background: #e0e0e0;color: #636363;\"><span class=\"ubtn-data ubtn-icon\"><i class=\"dt-icon-the7-download\" style=\"font-size:0px;color:#c38839;\"><\/i><\/span><span class=\"ubtn-hover\" style=\"background-color:\"><\/span><span class=\"ubtn-data ubtn-text \" >SCARICA IL CATALOGO<\/span><\/button><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"ult-spacer spacer-6a045163e8549\" data-id=\"6a045163e8549\" data-height=\"120\" data-height-mobile=\"40\" data-height-tab=\"80\" data-height-tab-portrait=\"80\" data-height-mobile-landscape=\"40\" style=\"clear:both;display:block;\"><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span  class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span  class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1751889934036 new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #636363;\">COLORI<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Surface Greige<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1754054658321\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000.jpg\" target=\"_self\" data-large_image_width=\"1000\" data-large_image_height=\"1000\"  class=\"vc_single_image-wrapper   vc_box_border_grey dt-pswp-item rollover rollover-zoom\"   ><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000-300x300.jpg\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000-300x300.jpg 300w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000-150x150.jpg 150w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000-768x768.jpg 768w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Greige1000.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/surface2\/greige1000\/\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"ult-spacer spacer-6a045163e92e6\" data-id=\"6a045163e92e6\" data-height=\"60\" data-height-mobile=\"20\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Surface Sand<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1754054672458\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000.jpg\" target=\"_self\" data-large_image_width=\"1000\" data-large_image_height=\"1000\"  class=\"vc_single_image-wrapper   vc_box_border_grey dt-pswp-item rollover rollover-zoom\"   ><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000-300x300.jpg\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000-300x300.jpg 300w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000-150x150.jpg 150w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000-768x768.jpg 768w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/Sand1000.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/surface2\/sand1000\/\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"ult-spacer spacer-6a045163e987d\" data-id=\"6a045163e987d\" data-height=\"60\" data-height-mobile=\"20\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Surface White<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1754054685785\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000.jpg\" target=\"_self\" data-large_image_width=\"1000\" data-large_image_height=\"1000\"  class=\"vc_single_image-wrapper   vc_box_border_grey dt-pswp-item rollover rollover-zoom\"   ><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000-300x300.jpg\" class=\"vc_single_image-img attachment-medium\" alt=\"\" srcset=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000-300x300.jpg 300w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000-150x150.jpg 150w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000-768x768.jpg 768w, https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/White1000.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/surface2\/white1000\/\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"ult-spacer spacer-6a045163e9e75\" data-id=\"6a045163e9e75\" data-height=\"60\" data-height-mobile=\"20\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span  class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span  class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1751890009944 new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #636363;\">FORMATI<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"71\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/06\/60x60.png\" class=\"vc_single_image-img attachment-full\" alt=\"\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/alpi2\/60x60\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"105\" height=\"104\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/06\/90x90.png\" class=\"vc_single_image-img attachment-full\" alt=\"\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/alpi2\/90x90\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>60X60<br \/>\nRETT R10 8MM<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>90X90<br \/>\nRETT R10 9MM<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"139\" height=\"71\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/06\/60x120.png\" class=\"vc_single_image-img attachment-full\" alt=\"\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/alpi2\/60x120\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"139\" height=\"139\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/07\/120x120.png\" class=\"vc_single_image-img attachment-full\" alt=\"\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/space2\/120x120-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>60X120<br \/>\nRETT R10 8MM<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>120X120 XXL<br \/>\nRETT R10 9MM<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span  class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span  class=\"vc_sep_line\"><\/span><\/span>\n<\/div><div class=\"ult-spacer spacer-6a045163eb502\" data-id=\"6a045163eb502\" data-height=\"60\" data-height-mobile=\"20\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  vc_custom_1751890140743 new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #636363;\">ACCESSORI<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"97\" height=\"26\" src=\"https:\/\/www.ceramicaflaminia.com\/wp-content\/uploads\/2025\/06\/Battiscopa-1.png\" class=\"vc_single_image-img attachment-full\" alt=\"\"  data-dt-location=\"https:\/\/www.ceramicaflaminia.com\/it_it\/project\/alpi2\/battiscopa-3\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element  new-font\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Battiscopa<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"ult-spacer spacer-6a045163ebaad\" data-id=\"6a045163ebaad\" data-height=\"60\" data-height-mobile=\"20\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"20\" style=\"clear:both;display:block;\"><\/div><\/div><\/div><\/div><\/div><!-- Row Backgrounds --><div class=\"upb_color\" data-bg-override=\"ex-full\" data-bg-color=\"rgba(195,136,57,0.04)\" data-fadeout=\"\" data-fadeout-percentage=\"30\" data-parallax-content=\"\" data-parallax-content-sense=\"30\" data-row-effect-mobile-disable=\"true\" data-img-parallax-mobile-disable=\"true\" data-rtl=\"false\"  data-custom-vc-row=\"\"  data-vc=\"6.4.1\"  data-is_old_vc=\"\"  data-theme-support=\"\"   data-overlay=\"false\" data-overlay-color=\"\" data-overlay-pattern=\"\" data-overlay-pattern-opacity=\"\" data-overlay-pattern-size=\"\"    ><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SURFACE Surface di Ceramica Flaminia \u00e8 una collezione di piastrelle in gres porcellanato che esplora la materia con superfici minimali e sofisticate. Proposta nei colori White, Greige e Sand, e nei formati rettificati 60\u00d760, 90\u00d790 e 60\u00d7120, si distingue per la sua texture morbida e neutra, capace di valorizzare ambienti moderni con equilibrio e sobriet\u00e0.&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2425,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[15],"dt_portfolio_tags":[],"class_list":["post-2557","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-collection-newsite","dt_portfolio_category-15","description-off"],"_links":{"self":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":13,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio\/2557\/revisions"}],"predecessor-version":[{"id":3141,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio\/2557\/revisions\/3141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/media\/2425"}],"wp:attachment":[{"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio_category?post=2557"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.ceramicaflaminia.com\/it_it\/wp-json\/wp\/v2\/dt_portfolio_tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}